{"id":4933,"date":"2021-09-30T08:00:00","date_gmt":"2021-09-30T07:00:00","guid":{"rendered":"https:\/\/www.stretchhood.it\/nouvelles\/bocedi-q-a\/"},"modified":"2021-12-30T10:21:09","modified_gmt":"2021-12-30T09:21:09","slug":"bocedi-q-a","status":"publish","type":"post","link":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/","title":{"rendered":"Bocedi Q&#038;A (Questions et R\u00e9ponses)"},"content":{"rendered":"<div class=\"wp-block-getwid-images-slider has-arrows-inside has-dots-inside has-images-center has-cropped-images\"><div class=\"wp-block-getwid-images-slider__wrapper\" data-effect=\"fade\" data-slides-show=\"1\" data-slides-show-laptop=\"1\" data-slides-show-tablet=\"1\" data-slides-show-mobile=\"1\" data-slides-scroll=\"1\" data-autoplay=\"true\" data-autoplay-speed=\"1000\" data-infinite=\"true\" data-animation-speed=\"800\" data-center-mode=\"false\" data-variable-width=\"false\" data-arrows=\"inside\" data-dots=\"inside\" data-spacing=\"none\"><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\" data-id=\"2734\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2734\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2734\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\" data-id=\"2735\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2735\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2735\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\" data-id=\"2736\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2736\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2736\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\" data-id=\"2737\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2737\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2737\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\" data-id=\"2738\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2738\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2738\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" data-id=\"2739\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2739\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2739\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><\/div><\/div>\r\n\n<h3 class=\"wp-block-heading\">Qu&rsquo;est-ce que le film \u00e0 housse \u00e9tirable?<\/h3>\n\n<p>La housse \u00e9tirable est un film <strong>tubulaire fourni<\/strong>\u00a0en bobines d&rsquo;un diam\u00e8tre moyen de 700 mm. Le film est constitu\u00e9 de plusieurs couches de\u00a0<strong>poly\u00e9thyl\u00e8ne basse densit\u00e9<\/strong>\u00a0pr\u00e9sentant d&rsquo;excellentes propri\u00e9t\u00e9s \u00e9lastiques. Cette technologie innovante\u00a0<strong>augmente l&rsquo;efficacit\u00e9 de l&#8217;emballage <\/strong>et\u00a0<strong>r\u00e9duit les co\u00fbts de manutention et de logistique<\/strong>\u00a0en garantissant une stabilit\u00e9 exceptionnelle de la charge, une protection contre les intemp\u00e9ries et les UV des produits emball\u00e9s.<\/p>\n\n<h3 class=\"wp-block-heading\">Le film \u00e0 housse \u00e9tirable peut-il \u00eatre imprim\u00e9?<\/h3>\n\n<p>Oui, le film \u00e0 housse \u00e9tirable peut \u00eatre imprim\u00e9 avec des graphiques personnalis\u00e9s dans un maximum de <strong>6 couleurs diff\u00e9rentes<\/strong>. Le film est \u00e9galement disponible enti\u00e8rement\u00a0<strong>color\u00e9<\/strong>, <strong>opaque<\/strong>\u00a0ou\u00a0<strong>transparent<\/strong>.<\/p>\n\n<h3 class=\"wp-block-heading\">Le film \u00e0 housse \u00e9tirable doit-il \u00eatre chauff\u00e9?<\/h3>\n\n<p>Non, le film \u00e0 housse \u00e9tirable <strong>n&rsquo;a pas besoin d&rsquo;\u00eatre chauff\u00e9<\/strong>. Le film poss\u00e8de d&rsquo;excellentes propri\u00e9t\u00e9s \u00e9lastiques, qui lui permettent d&rsquo;\u00eatre \u00e9tir\u00e9 et rel\u00e2ch\u00e9 autour de la charge, dans le respect total de la s\u00e9curit\u00e9 des produits, et compris les marchandises sensibles \u00e0 la chaleur.<\/p>\n\n<h3 class=\"wp-block-heading\">Le film \u00e0 housse \u00e9tirable peut-il \u00eatre recycl\u00e9?<\/h3>\n\n<p>Oui, le film \u00e0 housse\u00a0<strong>\u00e9tirable peut \u00eatre recycl\u00e9<\/strong>\u00a0et peut \u00e9galement \u00eatre fabriqu\u00e9 \u00e0 partir de mat\u00e9riaux recycl\u00e9s.<\/p>\n\n<h3 class=\"wp-block-heading\">O\u00f9 puis-je acheter du film \u00e0 housse \u00e9tirable?<\/h3>\n\n<p>Aujourd&rsquo;hui, il est possible d&rsquo;acheter du film \u00e0 housse \u00e9tirable aupr\u00e8s de fabricants\u00a0<strong>locaux<\/strong>\u00a0et\u00a0<strong>multinationaux<\/strong>\u00a0disposant d&rsquo;entrep\u00f4ts sur place, dans le monde entier.<\/p>\n\n<h3 class=\"wp-block-heading\">Quelle est la vitesse de fonctionnement de la machine \u00e0 housse \u00e9tirable Bocedi?<\/h3>\n\n<p>La machine \u00e0 housse \u00e9tirable Bocedi a une <strong>capacit\u00e9 flexible<\/strong>, elle peut \u00eatre r\u00e9gl\u00e9e de\u00a0<strong>1 palette\/heure \u00e0 280 palettes\/heure<\/strong>. Chaque machine est configur\u00e9e pour r\u00e9pondre aux exigences de capacit\u00e9 de production du client.<\/p>\n\n<h3 class=\"wp-block-heading\">Puis-je emballer des palettes de diff\u00e9rentes tailles?<\/h3>\n\n<p>Oui, les machines \u00e0 housse \u00e9tirable Bocedi\u00a0<strong>peuvent emballer diff\u00e9rents types de palettes dans la m\u00eame machine<\/strong>, le tout dans un cycle automatique. Pour encore plus de flexibilit\u00e9, les machines \u00e0 housse \u00e9tirable Bocedi peuvent \u00eatre configur\u00e9es avec plusieurs bobines de film (jusqu&rsquo;\u00e0 6), la taille de la bobine est\u00a0<strong>automatiquement s\u00e9lectionn\u00e9e<\/strong>\u00a0par la machine.<\/p>\n\n<h3 class=\"wp-block-heading\">Puis-je emballer des charges de diff\u00e9rentes hauteurs?<\/h3>\n\n<p>Oui, gr\u00e2ce au syst\u00e8me int\u00e9gr\u00e9 de lecture automatique de la hauteur des palettes. Ce syst\u00e8me permet aux machines \u00e0 housse \u00e9tirable Bocedi de\u00a0<strong>pr\u00e9parer la bonne quantit\u00e9 de film pour la charge entrante<\/strong>, optimisant ainsi l&rsquo;utilisation du mat\u00e9riel d&#8217;emballage et \u00e9vitant les d\u00e9chets.<\/p>\n\n<h3 class=\"wp-block-heading\">La stabilit\u00e9 des charges emball\u00e9es avec la machine \u00e0 housse \u00e9tirable Bocedi est \u00e9gale \u00e0 celle des charges emball\u00e9es avec une housse r\u00e9tractable ou un film \u00e9tirable?<\/h3>\n\n<p>Non, la stabilit\u00e9 des charges emball\u00e9es est\u00a0<strong>meilleure<\/strong>. L&#8217;emballage sous housse \u00e9tirable a une couverture de la charge plus uniforme et plus \u00e9lastique, ce qui le rend adapt\u00e9 \u00e0 tous les types de charges, y compris les charges instables et de forme irr\u00e9guli\u00e8re. Gr\u00e2ce \u00e0 ses propri\u00e9t\u00e9s \u00e9lastiques sup\u00e9rieures, la housse \u00e9tirable <strong>s\u00e9curise les charges avec moins de film<\/strong>\u00a0que les autres proc\u00e9d\u00e9s d&#8217;emballage.<\/p>\n\n<h3 class=\"wp-block-heading\">Le co\u00fbt de l&#8217;emballage sous housse \u00e9tirable est-il plus \u00e9lev\u00e9 que celui de l&#8217;emballage sous film \u00e9tirable ou de la housse r\u00e9tractable?<\/h3>\n\n<p>Non, le co\u00fbt de l&#8217;emballage sous housse \u00e9tirable n&rsquo;est pas plus \u00e9lev\u00e9. Le co\u00fbt du film de la housse \u00e9tirable est l\u00e9g\u00e8rement plus \u00e9lev\u00e9, mais la consommation de mat\u00e9riau de la housse \u00e9tirable est plus faible et permet des\u00a0<strong>\u00e9conomies de plastique<\/strong>\u00a0importantes et responsables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qu&rsquo;est-ce que le film \u00e0 housse \u00e9tirable? La housse \u00e9tirable est un film tubulaire fourni\u00a0en bobines d&rsquo;un diam\u00e8tre moyen de 700 mm. Le film est constitu\u00e9 de plusieurs couches de\u00a0poly\u00e9thyl\u00e8ne basse densit\u00e9\u00a0pr\u00e9sentant d&rsquo;excellentes propri\u00e9t\u00e9s \u00e9lastiques. Cette technologie innovante\u00a0augmente l&rsquo;efficacit\u00e9 de l&#8217;emballage et\u00a0r\u00e9duit les co\u00fbts de manutention et de logistique\u00a0en garantissant une stabilit\u00e9 exceptionnelle de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bocedi Q&amp;A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bocedi Q&amp;A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl\" \/>\n<meta property=\"og:description\" content=\"Qu&rsquo;est-ce que le film \u00e0 housse \u00e9tirable? La housse \u00e9tirable est un film tubulaire fourni\u00a0en bobines d&rsquo;un diam\u00e8tre moyen de 700 mm. Le film est constitu\u00e9 de plusieurs couches de\u00a0poly\u00e9thyl\u00e8ne basse densit\u00e9\u00a0pr\u00e9sentant d&rsquo;excellentes propri\u00e9t\u00e9s \u00e9lastiques. Cette technologie innovante\u00a0augmente l&rsquo;efficacit\u00e9 de l&#8217;emballage et\u00a0r\u00e9duit les co\u00fbts de manutention et de logistique\u00a0en garantissant une stabilit\u00e9 exceptionnelle de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Bocedi srl\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-30T09:21:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"davidevs1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"davidevs1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\"},\"author\":{\"name\":\"davidevs1\",\"@id\":\"https:\/\/bocedisrl.com\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86\"},\"headline\":\"Bocedi Q&#038;A (Questions et R\u00e9ponses)\",\"datePublished\":\"2021-09-30T07:00:00+00:00\",\"dateModified\":\"2021-12-30T09:21:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\"},\"wordCount\":585,\"publisher\":{\"@id\":\"https:\/\/bocedisrl.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"articleSection\":[\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\",\"url\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\",\"name\":\"Bocedi Q&A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl\",\"isPartOf\":{\"@id\":\"https:\/\/bocedisrl.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"datePublished\":\"2021-09-30T07:00:00+00:00\",\"dateModified\":\"2021-12-30T09:21:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage\",\"url\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"contentUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bocedisrl.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\",\"item\":\"https:\/\/stretchhood.it\/fr\/category\/nouvelles\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bocedi Q&#038;A (Questions et R\u00e9ponses)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bocedisrl.com\/#website\",\"url\":\"https:\/\/bocedisrl.com\/\",\"name\":\"Bocedi srl\",\"description\":\"Pallet Packaging Systems\",\"publisher\":{\"@id\":\"https:\/\/bocedisrl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bocedisrl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bocedisrl.com\/#organization\",\"name\":\"Bocedi srl\",\"url\":\"https:\/\/bocedisrl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bocedisrl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"contentUrl\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"width\":800,\"height\":480,\"caption\":\"Bocedi srl\"},\"image\":{\"@id\":\"https:\/\/bocedisrl.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/bocedisrl.com\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86\",\"name\":\"davidevs1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/bocedisrl.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g\",\"caption\":\"davidevs1\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bocedi Q&A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/","og_locale":"fr_FR","og_type":"article","og_title":"Bocedi Q&A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl","og_description":"Qu&rsquo;est-ce que le film \u00e0 housse \u00e9tirable? La housse \u00e9tirable est un film tubulaire fourni\u00a0en bobines d&rsquo;un diam\u00e8tre moyen de 700 mm. Le film est constitu\u00e9 de plusieurs couches de\u00a0poly\u00e9thyl\u00e8ne basse densit\u00e9\u00a0pr\u00e9sentant d&rsquo;excellentes propri\u00e9t\u00e9s \u00e9lastiques. Cette technologie innovante\u00a0augmente l&rsquo;efficacit\u00e9 de l&#8217;emballage et\u00a0r\u00e9duit les co\u00fbts de manutention et de logistique\u00a0en garantissant une stabilit\u00e9 exceptionnelle de la [&hellip;]","og_url":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/","og_site_name":"Bocedi srl","article_published_time":"2021-09-30T07:00:00+00:00","article_modified_time":"2021-12-30T09:21:09+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","type":"image\/jpeg"}],"author":"davidevs1","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"davidevs1","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#article","isPartOf":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/"},"author":{"name":"davidevs1","@id":"https:\/\/bocedisrl.com\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86"},"headline":"Bocedi Q&#038;A (Questions et R\u00e9ponses)","datePublished":"2021-09-30T07:00:00+00:00","dateModified":"2021-12-30T09:21:09+00:00","mainEntityOfPage":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/"},"wordCount":585,"publisher":{"@id":"https:\/\/bocedisrl.com\/#organization"},"image":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage"},"thumbnailUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","articleSection":["Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/","url":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/","name":"Bocedi Q&A (Questions et R\u00e9ponses) - Nouvelles - Bocedi srl","isPartOf":{"@id":"https:\/\/bocedisrl.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage"},"image":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage"},"thumbnailUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","datePublished":"2021-09-30T07:00:00+00:00","dateModified":"2021-12-30T09:21:09+00:00","breadcrumb":{"@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#primaryimage","url":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","contentUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/stretchhood.it\/fr\/nouvelles\/bocedi-q-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bocedisrl.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvelles","item":"https:\/\/stretchhood.it\/fr\/category\/nouvelles\/"},{"@type":"ListItem","position":3,"name":"Bocedi Q&#038;A (Questions et R\u00e9ponses)"}]},{"@type":"WebSite","@id":"https:\/\/bocedisrl.com\/#website","url":"https:\/\/bocedisrl.com\/","name":"Bocedi srl","description":"Pallet Packaging Systems","publisher":{"@id":"https:\/\/bocedisrl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bocedisrl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/bocedisrl.com\/#organization","name":"Bocedi srl","url":"https:\/\/bocedisrl.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bocedisrl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","contentUrl":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","width":800,"height":480,"caption":"Bocedi srl"},"image":{"@id":"https:\/\/bocedisrl.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bocedisrl.com\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86","name":"davidevs1","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/bocedisrl.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g","caption":"davidevs1"}}]}},"_links":{"self":[{"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/posts\/4933"}],"collection":[{"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/comments?post=4933"}],"version-history":[{"count":1,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/posts\/4933\/revisions"}],"predecessor-version":[{"id":4934,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/posts\/4933\/revisions\/4934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/media\/3733"}],"wp:attachment":[{"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/media?parent=4933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/categories?post=4933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stretchhood.it\/fr\/wp-json\/wp\/v2\/tags?post=4933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}