{"id":4935,"date":"2021-09-30T08:00:00","date_gmt":"2021-09-30T07:00:00","guid":{"rendered":"https:\/\/www.stretchhood.it\/news\/bocedi-q-a\/"},"modified":"2021-12-30T10:26:16","modified_gmt":"2021-12-30T09:26:16","slug":"bocedi-q-a","status":"publish","type":"post","link":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/","title":{"rendered":"Bocedi Q&#038;A (Preguntas y Respuestas)"},"content":{"rendered":"<div class=\"wp-block-getwid-images-slider has-arrows-inside has-dots-inside has-images-center has-cropped-images\"><div class=\"wp-block-getwid-images-slider__wrapper\" data-effect=\"fade\" data-slides-show=\"1\" data-slides-show-laptop=\"1\" data-slides-show-tablet=\"1\" data-slides-show-mobile=\"1\" data-slides-scroll=\"1\" data-autoplay=\"true\" data-autoplay-speed=\"1000\" data-infinite=\"true\" data-animation-speed=\"800\" data-center-mode=\"false\" data-variable-width=\"false\" data-arrows=\"inside\" data-dots=\"inside\" data-spacing=\"none\"><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\" data-id=\"2734\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2734\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2734\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-01-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\" data-id=\"2735\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2735\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2735\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-02-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\" data-id=\"2736\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2736\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2736\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-03-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\" data-id=\"2737\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2737\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2737\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-04-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\" data-id=\"2738\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2738\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2738\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-05-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><div class=\"wp-block-getwid-images-slider__item\"><a href=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" data-id=\"2739\" data-link=\"https:\/\/www.stretchhood.it\/?attachment_id=2739\" data-original-link=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" class=\"wp-block-getwid-images-slider__image wp-image-2739\" srcset=\"https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg 1200w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06-980x653.jpg 980w, https:\/\/www.stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06-480x320.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1200px, 100vw\" \/><\/figure><\/a><\/div><\/div><\/div>\r\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 es la pel\u00edcula stretch hood?<\/h3>\n\n<p>El film stertch hood es un <strong>film tubular<\/strong>\u00a0que se suministra en bobinas de 700 mm de di\u00e1metro, fabricado con capas de <strong>polietileno de baja densidad<\/strong>\u00a0con excelentes propiedades el\u00e1sticas. Esta innovadora tecnolog\u00eda aumenta la eficacia del envasado y\u00a0<strong>reduce los costes de manipulaci\u00f3n y log\u00edstica<\/strong>, garantizando la completa impermeabilidad y la protecci\u00f3n contra los rayos UV de los envases.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfSe puede imprimir el film stertch hood?<\/h3>\n\n<p>S\u00ed, el film stretch hood se puede imprimir con gr\u00e1ficos personalizados en hasta\u00a0<strong>6 colores diferentes<\/strong>. Est\u00e1 disponible en <strong>colores<\/strong>,\u00a0<strong>opaco<\/strong>\u00a0o\u00a0<strong>transparente<\/strong>.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfEs necesario calentar el film stretch hood?<\/h3>\n\n<p>No, el film stertch hood\u00a0<strong>no necesita ser calentado<\/strong>. Las pel\u00edculas tienen muy buenas propiedades el\u00e1sticas, lo que permite estirarlas y soltarlas alrededor de la carga, respetando la seguridad y los productos, incluidos los que son sensibles al calor.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfSe puede reciclar el film stretch hood?<\/h3>\n\n<p>S\u00ed, el film stretch hood\u00a0<strong>se puede reciclar<\/strong>\u00a0y se puede fabricar con materiales reciclados.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfD\u00f3nde puedo comprar el film stretch hood?<\/h3>\n\n<p>Hoy en d\u00eda es posible comprar film stretch hood de fabricantes <strong>locales<\/strong>\u00a0y\u00a0<strong>multinacionales<\/strong>\u00a0con almacenes en todo el mundo.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfA qu\u00e9 velocidad funciona la m\u00e1quina de enfundado Bocedi?<\/h3>\n\n<p>La enfundadora Bocedi trabaja desde\u00a0<strong>1 palet\/hora hasta 280palets\/hora<\/strong>. Cada m\u00e1quina\u00a0se configura para satisfacer la <strong>capacidad de producci\u00f3n requerida<\/strong>\u00a0por parte del cliente.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfPuedo embalar palets de diferentes tama\u00f1os?<\/h3>\n\n<p>S\u00ed, las enfundadoras Bocedi\u00a0<strong>pueden embalar diferentes tipos de palets<\/strong>\u00a0en la misma sesi\u00f3n de encapuchado, en ciclo autom\u00e1tico y con la ayuda de una sola bobina. Para una mayor flexibilidad, las enfundadoras Bocedi pueden configurarse para trabajar con m\u00faltiples bobinas a la vez, que son\u00a0<strong>elegidas autom\u00e1ticamente<\/strong>\u00a0por la encapuchadora.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfPuedo embalar cargas de diferentes alturas?<\/h3>\n\n<p>S\u00ed, gracias al sistema de lectura autom\u00e1tica de la altura de las paletas. El sistema permite a las m\u00e1quinas enfundadoras Bocedi preparar la cantidad correcta de pel\u00edcula para la carga entrante,\u00a0<strong>optimizando el uso del material de embalaje<\/strong>\u00a0y evitando el desperdicio, evitar el despilfarro.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfLa estabilidad de las cargas embaladas con la enfundadora stretch Bocedi es igual a la de envasado con un envolvedora o con termo retracci\u00f3n?<\/h3>\n\n<p>No, la estabilidad de las cargas encapuchadas es\u00a0<strong>mejor<\/strong>. El embalaje con stretch hood consiste en una sola capa m\u00e1s homog\u00e9nea y el\u00e1stica, lo que se revela perfecto tambi\u00e9n para cargas dif\u00edciles y de forma irregular. Gracias a las excellentes propiedades el\u00e1sticas el stretch hood conlleva el\u00a0<strong>uso de menos film<\/strong>\u00a0en comparaci\u00f3n con otros procesos de embalaje.<\/p>\n\n<h3 class=\"wp-block-heading\">\u00bfEs m\u00e1s caro el coste del embalaje stretch hood con respecto al coste del embalaje con envolvedora y termo retracci\u00f3n?<\/h3>\n\n<p>No, el coste de embalaje con stretch hood \u00a0no es m\u00e1s caro. El coste del film stretch hood es ligeramente superior, sin embargo el consumo de material para las capuchas es\u00a0<strong>menor<\/strong>\u00a0y proporciona un\u00a0<strong>ahorro significativo y responsable de pl\u00e1sticos<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es la pel\u00edcula stretch hood? El film stertch hood es un film tubular\u00a0que se suministra en bobinas de 700 mm de di\u00e1metro, fabricado con capas de polietileno de baja densidad\u00a0con excelentes propiedades el\u00e1sticas. Esta innovadora tecnolog\u00eda aumenta la eficacia del envasado y\u00a0reduce los costes de manipulaci\u00f3n y log\u00edstica, garantizando la completa impermeabilidad y la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[14],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bocedi Q&amp;A (Preguntas y Respuestas) - News - Bocedi srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bocedi Q&amp;A (Preguntas y Respuestas) - News - Bocedi srl\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 es la pel\u00edcula stretch hood? El film stertch hood es un film tubular\u00a0que se suministra en bobinas de 700 mm de di\u00e1metro, fabricado con capas de polietileno de baja densidad\u00a0con excelentes propiedades el\u00e1sticas. Esta innovadora tecnolog\u00eda aumenta la eficacia del envasado y\u00a0reduce los costes de manipulaci\u00f3n y log\u00edstica, garantizando la completa impermeabilidad y la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Bocedi srl\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-30T09:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"davidevs1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"davidevs1\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\"},\"author\":{\"name\":\"davidevs1\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86\"},\"headline\":\"Bocedi Q&#038;A (Preguntas y Respuestas)\",\"datePublished\":\"2021-09-30T07:00:00+00:00\",\"dateModified\":\"2021-12-30T09:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\"},\"wordCount\":515,\"publisher\":{\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\",\"url\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\",\"name\":\"Bocedi Q&A (Preguntas y Respuestas) - News - Bocedi srl\",\"isPartOf\":{\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"datePublished\":\"2021-09-30T07:00:00+00:00\",\"dateModified\":\"2021-12-30T09:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage\",\"url\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"contentUrl\":\"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bocedisrl.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/stretchhood.it\/es\/category\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bocedi Q&#038;A (Preguntas y Respuestas)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#website\",\"url\":\"https:\/\/mail.stretchhood.it\/es\/\",\"name\":\"Bocedi srl\",\"description\":\"Pallet Packaging Systems\",\"publisher\":{\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mail.stretchhood.it\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#organization\",\"name\":\"Bocedi srl\",\"url\":\"https:\/\/mail.stretchhood.it\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"contentUrl\":\"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png\",\"width\":800,\"height\":480,\"caption\":\"Bocedi srl\"},\"image\":{\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86\",\"name\":\"davidevs1\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g\",\"caption\":\"davidevs1\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bocedi Q&A (Preguntas y Respuestas) - News - Bocedi srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/","og_locale":"es_ES","og_type":"article","og_title":"Bocedi Q&A (Preguntas y Respuestas) - News - Bocedi srl","og_description":"\u00bfQu\u00e9 es la pel\u00edcula stretch hood? El film stertch hood es un film tubular\u00a0que se suministra en bobinas de 700 mm de di\u00e1metro, fabricado con capas de polietileno de baja densidad\u00a0con excelentes propiedades el\u00e1sticas. Esta innovadora tecnolog\u00eda aumenta la eficacia del envasado y\u00a0reduce los costes de manipulaci\u00f3n y log\u00edstica, garantizando la completa impermeabilidad y la [&hellip;]","og_url":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/","og_site_name":"Bocedi srl","article_published_time":"2021-09-30T07:00:00+00:00","article_modified_time":"2021-12-30T09:26:16+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","type":"image\/jpeg"}],"author":"davidevs1","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"davidevs1","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#article","isPartOf":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/"},"author":{"name":"davidevs1","@id":"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86"},"headline":"Bocedi Q&#038;A (Preguntas y Respuestas)","datePublished":"2021-09-30T07:00:00+00:00","dateModified":"2021-12-30T09:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/"},"wordCount":515,"publisher":{"@id":"https:\/\/mail.stretchhood.it\/es\/#organization"},"image":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage"},"thumbnailUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/","url":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/","name":"Bocedi Q&A (Preguntas y Respuestas) - News - Bocedi srl","isPartOf":{"@id":"https:\/\/mail.stretchhood.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage"},"image":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage"},"thumbnailUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","datePublished":"2021-09-30T07:00:00+00:00","dateModified":"2021-12-30T09:26:16+00:00","breadcrumb":{"@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#primaryimage","url":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","contentUrl":"https:\/\/stretchhood.it\/wp-content\/uploads\/2021\/12\/news-2021-09-30-image-06.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/stretchhood.it\/es\/news\/bocedi-q-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bocedisrl.com\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/stretchhood.it\/es\/category\/news\/"},{"@type":"ListItem","position":3,"name":"Bocedi Q&#038;A (Preguntas y Respuestas)"}]},{"@type":"WebSite","@id":"https:\/\/mail.stretchhood.it\/es\/#website","url":"https:\/\/mail.stretchhood.it\/es\/","name":"Bocedi srl","description":"Pallet Packaging Systems","publisher":{"@id":"https:\/\/mail.stretchhood.it\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.stretchhood.it\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.stretchhood.it\/es\/#organization","name":"Bocedi srl","url":"https:\/\/mail.stretchhood.it\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.stretchhood.it\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","contentUrl":"https:\/\/www.bocedisrl.com\/wp-content\/uploads\/2021\/11\/logo-bocedi.png","width":800,"height":480,"caption":"Bocedi srl"},"image":{"@id":"https:\/\/mail.stretchhood.it\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/02a51e74945bac3c899a5b91a16dcb86","name":"davidevs1","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.stretchhood.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7569ebeb7736497276fc8eb57493bb7a?s=96&d=mm&r=g","caption":"davidevs1"}}]}},"_links":{"self":[{"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/posts\/4935"}],"collection":[{"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/comments?post=4935"}],"version-history":[{"count":1,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/posts\/4935\/revisions"}],"predecessor-version":[{"id":4936,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/posts\/4935\/revisions\/4936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/media\/3735"}],"wp:attachment":[{"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/media?parent=4935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/categories?post=4935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stretchhood.it\/es\/wp-json\/wp\/v2\/tags?post=4935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}